{"id":926,"date":"2010-04-05T11:33:15","date_gmt":"2010-04-05T09:33:15","guid":{"rendered":"https:\/\/eulatnetwork.org\/?p=926"},"modified":"2020-05-06T16:24:26","modified_gmt":"2020-05-06T14:24:26","slug":"negociaciones-del-acuerdo-de-asociacion-entre-la-ue-y-ca-balance-y-alternativas-abril-2010","status":"publish","type":"post","link":"https:\/\/eulatnetwork.org\/es\/negociaciones-del-acuerdo-de-asociacion-entre-la-ue-y-ca-balance-y-alternativas-abril-2010\/","title":{"rendered":"Negociaciones del Acuerdo de Asociaci\u00f3n entre la UE y CA: balance y alternativas, abril 2010"},"content":{"rendered":"<p>El documento aqu\u00ed presente recoge esfuerzos y an\u00e1lisis de las organizaciones ALOP e Iniciativa CID. Su prop\u00f3sito es centrar la atenci\u00f3n de los gobiernos y actores decisivos de Centroam\u00e9rica en las consequencias negativas para el desarrollo que este acuerdo de asociaci\u00f3n con la Uni\u00f3n Europea traer\u00e1 a la regi\u00f3n (abril 2010)<\/p>\n<h2>Documentos relacionados<\/h2>\n<p>Documento<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El documento aqu\u00ed presente recoge esfuerzos y an\u00e1lisis de las organizaciones ALOP e Iniciativa CID. Su prop\u00f3sito es centrar la atenci\u00f3n de los gobiernos y actores decisivos de Centroam\u00e9rica en las consequencias negativas para el desarrollo que este acuerdo de asociaci\u00f3n con la Uni\u00f3n Europea traer\u00e1 a la regi\u00f3n (abril 2010) Documentos relacionados Documento<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[17,372],"tags":[],"class_list":["post-926","post","type-post","status-publish","format-standard","hentry","category-acuerdos-de-asociacion","category-relaciones-ue-america-latina","et-doesnt-have-format-content","et_post_format-et-post-format-standard"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Negociaciones del Acuerdo de Asociaci\u00f3n entre la UE y CA: balance y alternativas, abril 2010<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eulatnetwork.org\/es\/negociaciones-del-acuerdo-de-asociacion-entre-la-ue-y-ca-balance-y-alternativas-abril-2010\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Negociaciones del Acuerdo de Asociaci\u00f3n entre la UE y CA: balance y alternativas, abril 2010\" \/>\n<meta property=\"og:description\" content=\"El documento aqu\u00ed presente recoge esfuerzos y an\u00e1lisis de las organizaciones ALOP e Iniciativa CID. Su prop\u00f3sito es centrar la atenci\u00f3n de los gobiernos y actores decisivos de Centroam\u00e9rica en las consequencias negativas para el desarrollo que este acuerdo de asociaci\u00f3n con la Uni\u00f3n Europea traer\u00e1 a la regi\u00f3n (abril 2010) Documentos relacionados Documento\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eulatnetwork.org\/es\/negociaciones-del-acuerdo-de-asociacion-entre-la-ue-y-ca-balance-y-alternativas-abril-2010\/\" \/>\n<meta property=\"og:site_name\" content=\"EU-LAT\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CIFCA.Bruxelles\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-04-05T09:33:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-06T14:24:26+00:00\" \/>\n<meta name=\"author\" content=\"EU-LAT Network\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cifcabruselas\" \/>\n<meta name=\"twitter:site\" content=\"@cifcabruselas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"EU-LAT Network\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eulatnetwork.org\\\/es\\\/negociaciones-del-acuerdo-de-asociacion-entre-la-ue-y-ca-balance-y-alternativas-abril-2010\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eulatnetwork.org\\\/es\\\/negociaciones-del-acuerdo-de-asociacion-entre-la-ue-y-ca-balance-y-alternativas-abril-2010\\\/\"},\"author\":{\"name\":\"EU-LAT Network\",\"@id\":\"https:\\\/\\\/eulatnetwork.org\\\/es\\\/#\\\/schema\\\/person\\\/d7d57d7e552040d680cbae42386a19a3\"},\"headline\":\"Negociaciones del Acuerdo de Asociaci\u00f3n entre la UE y CA: balance y alternativas, abril 2010\",\"datePublished\":\"2010-04-05T09:33:15+00:00\",\"dateModified\":\"2020-05-06T14:24:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eulatnetwork.org\\\/es\\\/negociaciones-del-acuerdo-de-asociacion-entre-la-ue-y-ca-balance-y-alternativas-abril-2010\\\/\"},\"wordCount\":75,\"publisher\":{\"@id\":\"https:\\\/\\\/eulatnetwork.org\\\/es\\\/#organization\"},\"articleSection\":[\"Acuerdos de asociaci\u00f3n\",\"Relaciones UE-Am\u00e9rica Latina\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eulatnetwork.org\\\/es\\\/negociaciones-del-acuerdo-de-asociacion-entre-la-ue-y-ca-balance-y-alternativas-abril-2010\\\/\",\"url\":\"https:\\\/\\\/eulatnetwork.org\\\/es\\\/negociaciones-del-acuerdo-de-asociacion-entre-la-ue-y-ca-balance-y-alternativas-abril-2010\\\/\",\"name\":\"Negociaciones del Acuerdo de Asociaci\u00f3n entre la UE y CA: balance y alternativas, abril 2010\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eulatnetwork.org\\\/es\\\/#website\"},\"datePublished\":\"2010-04-05T09:33:15+00:00\",\"dateModified\":\"2020-05-06T14:24:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eulatnetwork.org\\\/es\\\/negociaciones-del-acuerdo-de-asociacion-entre-la-ue-y-ca-balance-y-alternativas-abril-2010\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eulatnetwork.org\\\/es\\\/negociaciones-del-acuerdo-de-asociacion-entre-la-ue-y-ca-balance-y-alternativas-abril-2010\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eulatnetwork.org\\\/es\\\/negociaciones-del-acuerdo-de-asociacion-entre-la-ue-y-ca-balance-y-alternativas-abril-2010\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/eulatnetwork.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Negociaciones del Acuerdo de Asociaci\u00f3n entre la UE y CA: balance y alternativas, abril 2010\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eulatnetwork.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/eulatnetwork.org\\\/es\\\/\",\"name\":\"EU-LAT\",\"description\":\"Advocacy Network - Red de Incidencia\",\"publisher\":{\"@id\":\"https:\\\/\\\/eulatnetwork.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eulatnetwork.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eulatnetwork.org\\\/es\\\/#organization\",\"name\":\"EU-LAT Network\",\"url\":\"https:\\\/\\\/eulatnetwork.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/eulatnetwork.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eulatnetwork.org\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/eulat_logotipo.png\",\"contentUrl\":\"https:\\\/\\\/eulatnetwork.org\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/eulat_logotipo.png\",\"width\":801,\"height\":224,\"caption\":\"EU-LAT Network\"},\"image\":{\"@id\":\"https:\\\/\\\/eulatnetwork.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CIFCA.Bruxelles\\\/\",\"https:\\\/\\\/x.com\\\/cifcabruselas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eulatnetwork.org\\\/es\\\/#\\\/schema\\\/person\\\/d7d57d7e552040d680cbae42386a19a3\",\"name\":\"EU-LAT Network\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d137e83018173050d5c9abb94fae9ab5b6a619d923ec76e9836769d16319ca7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d137e83018173050d5c9abb94fae9ab5b6a619d923ec76e9836769d16319ca7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d137e83018173050d5c9abb94fae9ab5b6a619d923ec76e9836769d16319ca7?s=96&d=mm&r=g\",\"caption\":\"EU-LAT Network\"},\"url\":\"https:\\\/\\\/eulatnetwork.org\\\/es\\\/author\\\/secretariado\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Negociaciones del Acuerdo de Asociaci\u00f3n entre la UE y CA: balance y alternativas, abril 2010","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eulatnetwork.org\/es\/negociaciones-del-acuerdo-de-asociacion-entre-la-ue-y-ca-balance-y-alternativas-abril-2010\/","og_locale":"es_ES","og_type":"article","og_title":"Negociaciones del Acuerdo de Asociaci\u00f3n entre la UE y CA: balance y alternativas, abril 2010","og_description":"El documento aqu\u00ed presente recoge esfuerzos y an\u00e1lisis de las organizaciones ALOP e Iniciativa CID. Su prop\u00f3sito es centrar la atenci\u00f3n de los gobiernos y actores decisivos de Centroam\u00e9rica en las consequencias negativas para el desarrollo que este acuerdo de asociaci\u00f3n con la Uni\u00f3n Europea traer\u00e1 a la regi\u00f3n (abril 2010) Documentos relacionados Documento","og_url":"https:\/\/eulatnetwork.org\/es\/negociaciones-del-acuerdo-de-asociacion-entre-la-ue-y-ca-balance-y-alternativas-abril-2010\/","og_site_name":"EU-LAT","article_publisher":"https:\/\/www.facebook.com\/CIFCA.Bruxelles\/","article_published_time":"2010-04-05T09:33:15+00:00","article_modified_time":"2020-05-06T14:24:26+00:00","author":"EU-LAT Network","twitter_card":"summary_large_image","twitter_creator":"@cifcabruselas","twitter_site":"@cifcabruselas","twitter_misc":{"Escrito por":"EU-LAT Network"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eulatnetwork.org\/es\/negociaciones-del-acuerdo-de-asociacion-entre-la-ue-y-ca-balance-y-alternativas-abril-2010\/#article","isPartOf":{"@id":"https:\/\/eulatnetwork.org\/es\/negociaciones-del-acuerdo-de-asociacion-entre-la-ue-y-ca-balance-y-alternativas-abril-2010\/"},"author":{"name":"EU-LAT Network","@id":"https:\/\/eulatnetwork.org\/es\/#\/schema\/person\/d7d57d7e552040d680cbae42386a19a3"},"headline":"Negociaciones del Acuerdo de Asociaci\u00f3n entre la UE y CA: balance y alternativas, abril 2010","datePublished":"2010-04-05T09:33:15+00:00","dateModified":"2020-05-06T14:24:26+00:00","mainEntityOfPage":{"@id":"https:\/\/eulatnetwork.org\/es\/negociaciones-del-acuerdo-de-asociacion-entre-la-ue-y-ca-balance-y-alternativas-abril-2010\/"},"wordCount":75,"publisher":{"@id":"https:\/\/eulatnetwork.org\/es\/#organization"},"articleSection":["Acuerdos de asociaci\u00f3n","Relaciones UE-Am\u00e9rica Latina"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/eulatnetwork.org\/es\/negociaciones-del-acuerdo-de-asociacion-entre-la-ue-y-ca-balance-y-alternativas-abril-2010\/","url":"https:\/\/eulatnetwork.org\/es\/negociaciones-del-acuerdo-de-asociacion-entre-la-ue-y-ca-balance-y-alternativas-abril-2010\/","name":"Negociaciones del Acuerdo de Asociaci\u00f3n entre la UE y CA: balance y alternativas, abril 2010","isPartOf":{"@id":"https:\/\/eulatnetwork.org\/es\/#website"},"datePublished":"2010-04-05T09:33:15+00:00","dateModified":"2020-05-06T14:24:26+00:00","breadcrumb":{"@id":"https:\/\/eulatnetwork.org\/es\/negociaciones-del-acuerdo-de-asociacion-entre-la-ue-y-ca-balance-y-alternativas-abril-2010\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eulatnetwork.org\/es\/negociaciones-del-acuerdo-de-asociacion-entre-la-ue-y-ca-balance-y-alternativas-abril-2010\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/eulatnetwork.org\/es\/negociaciones-del-acuerdo-de-asociacion-entre-la-ue-y-ca-balance-y-alternativas-abril-2010\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/eulatnetwork.org\/es\/"},{"@type":"ListItem","position":2,"name":"Negociaciones del Acuerdo de Asociaci\u00f3n entre la UE y CA: balance y alternativas, abril 2010"}]},{"@type":"WebSite","@id":"https:\/\/eulatnetwork.org\/es\/#website","url":"https:\/\/eulatnetwork.org\/es\/","name":"EU-LAT","description":"Advocacy Network - Red de Incidencia","publisher":{"@id":"https:\/\/eulatnetwork.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eulatnetwork.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/eulatnetwork.org\/es\/#organization","name":"EU-LAT Network","url":"https:\/\/eulatnetwork.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eulatnetwork.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/eulatnetwork.org\/wp-content\/uploads\/2018\/06\/eulat_logotipo.png","contentUrl":"https:\/\/eulatnetwork.org\/wp-content\/uploads\/2018\/06\/eulat_logotipo.png","width":801,"height":224,"caption":"EU-LAT Network"},"image":{"@id":"https:\/\/eulatnetwork.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CIFCA.Bruxelles\/","https:\/\/x.com\/cifcabruselas"]},{"@type":"Person","@id":"https:\/\/eulatnetwork.org\/es\/#\/schema\/person\/d7d57d7e552040d680cbae42386a19a3","name":"EU-LAT Network","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2d137e83018173050d5c9abb94fae9ab5b6a619d923ec76e9836769d16319ca7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2d137e83018173050d5c9abb94fae9ab5b6a619d923ec76e9836769d16319ca7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2d137e83018173050d5c9abb94fae9ab5b6a619d923ec76e9836769d16319ca7?s=96&d=mm&r=g","caption":"EU-LAT Network"},"url":"https:\/\/eulatnetwork.org\/es\/author\/secretariado\/"}]}},"_links":{"self":[{"href":"https:\/\/eulatnetwork.org\/es\/wp-json\/wp\/v2\/posts\/926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eulatnetwork.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eulatnetwork.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eulatnetwork.org\/es\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/eulatnetwork.org\/es\/wp-json\/wp\/v2\/comments?post=926"}],"version-history":[{"count":0,"href":"https:\/\/eulatnetwork.org\/es\/wp-json\/wp\/v2\/posts\/926\/revisions"}],"wp:attachment":[{"href":"https:\/\/eulatnetwork.org\/es\/wp-json\/wp\/v2\/media?parent=926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eulatnetwork.org\/es\/wp-json\/wp\/v2\/categories?post=926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eulatnetwork.org\/es\/wp-json\/wp\/v2\/tags?post=926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}